{"id":263,"count":1,"description":"","link":"https:\/\/hidcomcendekiabogor.sch.id\/info\/tag\/game-anak-indonesia\/","name":"Game Anak Indonesia","slug":"game-anak-indonesia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hidcomcendekiabogor.sch.id\/info\/wp-json\/wp\/v2\/tags\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hidcomcendekiabogor.sch.id\/info\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hidcomcendekiabogor.sch.id\/info\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hidcomcendekiabogor.sch.id\/info\/wp-json\/wp\/v2\/posts?tags=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}